{"id":8316,"date":"2025-01-27T13:09:39","date_gmt":"2025-01-27T13:09:39","guid":{"rendered":"https:\/\/villassardinia.net\/?post_type=luxury-villa&#038;p=8316"},"modified":"2025-01-27T13:09:39","modified_gmt":"2025-01-27T13:09:39","slug":"villa-ginepro","status":"publish","type":"luxury-villa","link":"https:\/\/villassardinia.net\/it\/luxury-villa\/villa-ginepro\/","title":{"rendered":"Villa Ginepro"},"content":{"rendered":"<div class=\"a53cbfa6de f17adf7576\" tabindex=\"0\"><strong>Vicolo Lentischio, 08020 San Teodoro, Italia<\/strong>\r\n<div class=\"ac52cd96ed\" aria-hidden=\"true\">\u00a0<\/div>\r\n<\/div>\r\n<p class=\"a53cbfa6de b3efd73f69\" data-testid=\"property-description\">Situata a San Teodoro, la Villa Ginepro con Piscina Privata offre sistemazioni climatizzate con piscina privata, vista sul giardino e patio.<\/p>\r\n<p class=\"a53cbfa6de b3efd73f69\" data-testid=\"property-description\">La struttura offre una vista serena sulla strada e si trova a 28 km dal Porto di Olbia e a 22 km dal Museo Archeologico di Olbia. Gli ospiti possono usufruire della connessione WiFi gratuita in tutta la struttura e l'Isola di Tavolara si trova a 8,1 km di distanza.<\/p>\r\n<p class=\"a53cbfa6de b3efd73f69\" data-testid=\"property-description\">Questa spaziosa villa comprende tre camere da letto, due bagni, lenzuola, asciugamani, un televisore con canali satellitari, una cucina completamente attrezzata e una terrazza che si affaccia sul mare.<\/p>\r\n<p class=\"a53cbfa6de b3efd73f69\" data-testid=\"property-description\">Per garantire la privacy, l'alloggio dispone di un ingresso privato. Inoltre, vi \u00e8 un giardino attrezzato con barbecue e gli ospiti hanno la possibilit\u00e0 di praticare il golf nelle vicinanze.<\/p>\r\n<p class=\"a53cbfa6de b3efd73f69\" data-testid=\"property-description\">La Chiesa di San Paolo Apostolo si trova a 23 km dalla villa, cos\u00ec come la Chiesa di San Simplicio.<\/p>\r\n<p class=\"a53cbfa6de b3efd73f69\" data-testid=\"property-description\">L'aeroporto di Olbia Costa Smeralda dista 17 km.<\/p>\r\n\r\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\r\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/villassardinia.net\/wp-content\/uploads\/2025\/01\/Villa-Ginepro-con-Piscina-Privata.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1023\" height=\"682\" data-id=\"8313\" class=\"wp-image-8313\" src=\"https:\/\/villassardinia.net\/wp-content\/uploads\/2025\/01\/Villa-Ginepro-con-Piscina-Privata.jpg\" alt=\"- Affitto Villa Sardegna\" title=\"- Ville Sardegna\"><\/a><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/villassardinia.net\/wp-content\/uploads\/2025\/01\/1737981538_929_Villa-Ginepro-con-Piscina-Privata.jpg\"><img decoding=\"async\" width=\"500\" height=\"333\" data-id=\"8314\" class=\"wp-image-8314\" src=\"https:\/\/villassardinia.net\/wp-content\/uploads\/2025\/01\/1737981538_929_Villa-Ginepro-con-Piscina-Privata.jpg\" alt=\"- Affitto Villa Sardegna\" title=\"- Ville Sardegna\"><\/a><\/figure>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/villassardinia.net\/wp-content\/uploads\/2025\/01\/1737981538_995_Villa-Ginepro-con-Piscina-Privata.jpg\"><img decoding=\"async\" width=\"500\" height=\"375\" data-id=\"8315\" class=\"wp-image-8315\" src=\"https:\/\/villassardinia.net\/wp-content\/uploads\/2025\/01\/1737981538_995_Villa-Ginepro-con-Piscina-Privata.jpg\" alt=\"- Affitto Villa Sardegna\" title=\"- Ville Sardegna\"><\/a><\/figure>\r\n<\/figure>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Villa Ginepro \u00e8 composta da tre camere da letto, due bagni, biancheria da letto, asciugamani, una televisione con canali satellitari, una cucina completamente attrezzata e una terrazza con vista sul mare.<\/p>","protected":false},"featured_media":8318,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":24,"footnotes":""},"location":[223],"class_list":["post-8316","luxury-villa","type-luxury-villa","status-publish","has-post-thumbnail","hentry","location-olbia"],"acf":[],"_links":{"self":[{"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/luxury-villa\/8316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/luxury-villa"}],"about":[{"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/types\/luxury-villa"}],"replies":[{"embeddable":true,"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/comments?post=8316"}],"version-history":[{"count":0,"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/luxury-villa\/8316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/media\/8318"}],"wp:attachment":[{"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/media?parent=8316"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/villassardinia.net\/it\/wp-json\/wp\/v2\/location?post=8316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}